{"id":71702,"date":"2024-08-30T01:16:00","date_gmt":"2024-08-29T15:16:00","guid":{"rendered":"https:\/\/www.icmarkets.com\/blog\/?p=71702"},"modified":"2024-10-04T15:40:35","modified_gmt":"2024-10-04T05:40:35","slug":"us-labor-day-trading-schedule-2024","status":"publish","type":"post","link":"https:\/\/ic.com\/blog\/us-labor-day-trading-schedule-2024\/","title":{"rendered":"US Labor Day Trading Schedule 2024"},"content":{"rendered":"\n<p>Dear Client,<\/p>\n\n\n\n<p>Please find our updated Trading schedule and general information related to the&nbsp;<strong>US Labor Day&nbsp;<\/strong>on&nbsp;<strong>Monday, 2 September, 2024<\/strong>.<\/p>\n\n\n\n<p>Liquidity over the holidays is expected to be particularly thin so please take the necessary precaution to ensure that you are not affected by increased volatility, spreads and intermittent pricing.<\/p>\n\n\n\n<p>All times mentioned below are Platform time (<strong>GMT +3<\/strong>).<\/p>\n\n\n\n<p><strong>Forex &amp; Crypto Pairs:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"166\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-1024x166.png\" alt=\"\" class=\"wp-image-71703\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-1024x166.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-300x49.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-768x124.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-1536x249.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-2048x331.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Fx-Crypto-1200x194.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Precious Metals:<\/strong> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"655\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-1024x655.png\" alt=\"\" class=\"wp-image-71704\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-1024x655.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-300x192.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-768x491.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-1536x982.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-2048x1309.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Precious-Metals-1200x767.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Spot Energies:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"220\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-1024x220.png\" alt=\"\" class=\"wp-image-71705\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-1024x220.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-300x64.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-768x165.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-1536x330.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-2048x440.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Spot-Energies-1200x258.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Indices:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"709\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-1024x709.png\" alt=\"\" class=\"wp-image-71706\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-1024x709.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-300x208.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-768x532.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-1536x1063.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-2048x1418.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-1-1200x831.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"655\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-1024x655.png\" alt=\"\" class=\"wp-image-71707\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-1024x655.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-300x192.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-768x491.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-1536x982.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-2048x1309.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-2-1200x767.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Energy Futures:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"165\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-1024x165.png\" alt=\"\" class=\"wp-image-71708\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-1024x165.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-300x48.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-768x124.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-1536x248.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-2048x331.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Energy-Futures-1200x194.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Soft Commodities Futures:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"492\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-1024x492.png\" alt=\"\" class=\"wp-image-71709\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-1024x492.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-300x144.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-768x369.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-1536x737.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-2048x983.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Soft-Commodities-Futures-1200x576.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Indices Futures:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"166\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-1024x166.png\" alt=\"\" class=\"wp-image-71710\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-1024x166.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-300x49.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-768x124.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-1536x249.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-2048x331.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Indices-futures-1200x194.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Bonds Futures:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"546\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-1024x546.png\" alt=\"\" class=\"wp-image-71711\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-1024x546.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-300x160.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-768x410.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-1536x819.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-2048x1092.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Bonds-Futures-1200x640.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Equities:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Equities.png\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"274\" src=\"https:\/\/www.icmarkets.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-1024x274.png\" alt=\"\" class=\"wp-image-71712\" srcset=\"https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-1024x274.png 1024w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-300x80.png 300w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-768x206.png 768w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-1536x411.png 1536w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-2048x549.png 2048w, https:\/\/ic.com\/blog\/wp-content\/uploads\/2024\/08\/Equities-1200x321.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Kind regards,<\/p>\n\n\n\n<p>IC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dear Client,<\/p>\n<p>Please find our updated Trading schedule and general information related to the\u00a0US Labor Day\u00a0on\u00a0Monday, 2 September, 2024.<\/p>\n","protected":false},"author":8,"featured_media":72316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[340,197],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/posts\/71702"}],"collection":[{"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/comments?post=71702"}],"version-history":[{"count":2,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/posts\/71702\/revisions"}],"predecessor-version":[{"id":72317,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/posts\/71702\/revisions\/72317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/media\/72316"}],"wp:attachment":[{"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/media?parent=71702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/categories?post=71702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ic.com\/blog\/wp-json\/wp\/v2\/tags?post=71702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}